
{"id":82,"date":"2025-08-22T13:56:30","date_gmt":"2025-08-22T11:56:30","guid":{"rendered":"https:\/\/fba-rc.be\/?page_id=82"},"modified":"2026-02-15T19:56:48","modified_gmt":"2026-02-15T18:56:48","slug":"ldmaatschap","status":"publish","type":"page","link":"https:\/\/fba-rc.be\/fr\/ldmaatschap\/","title":{"rendered":"L'adh\u00e9sion"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"82\" class=\"elementor elementor-82\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9637750 e-flex e-con-boxed e-con e-parent\" data-id=\"9637750\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-db96c6c e-con-full e-flex e-con e-child\" data-id=\"db96c6c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c237371 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c237371\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">L'adh\u00e9sion<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7bb5991 e-flex e-con-boxed e-con e-child\" data-id=\"7bb5991\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b86726d e-con-full e-flex e-con e-child\" data-id=\"b86726d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1107ae elementor-widget elementor-widget-heading\" data-id=\"b1107ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A: Licence MEMBER : 10\u20ac<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcb7676 e-con-full e-flex e-con e-child\" data-id=\"bcb7676\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0190701 elementor-widget elementor-widget-text-editor\" data-id=\"0190701\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La licence de membre constitue l'affiliation de base. Toute personne se trouvant sur un circuit en dehors de la zone r\u00e9serv\u00e9e aux spectateurs DOIT \u00eatre titulaire de cette licence et des assurances compl\u00e9mentaires qui y sont li\u00e9es. Elle est valable sur tous les circuits permanents et temporaires des clubs agr\u00e9\u00e9s par la FBA, lors des entra\u00eenements, des comp\u00e9titions ouvertes, des d\u00e9placements de clubs et lors de l'ex\u00e9cution de t\u00e2ches pendant les comp\u00e9titions (aide \u00e0 l'organisation, buffet, etc.).<\/p><p>La licence de membre n'est pas valable pour participer aux comp\u00e9titions du championnat belge, \u00e0 l'exception d'une seule manche, qui doit toutefois \u00eatre organis\u00e9e par le club qui vous a inscrit. Les licences sont enregistr\u00e9es par les comit\u00e9s des clubs dans le registre des membres et peuvent \u00eatre consult\u00e9es  sur le site de la FBA sous la rubrique \u00ab membres \u00bb.<\/p><div id=\"ConnectiveDocSignExtentionInstalled\" data-extension-version=\"1.0.4\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ce3c38 e-flex e-con-boxed e-con e-child\" data-id=\"0ce3c38\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5915150 e-con-full e-flex e-con e-child\" data-id=\"5915150\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d285710 elementor-widget elementor-widget-heading\" data-id=\"d285710\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B: Licence FBA FULL : 20\u20ac<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53efbfb e-con-full e-flex e-con e-child\" data-id=\"53efbfb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16996d2 elementor-widget elementor-widget-text-editor\" data-id=\"16996d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Si vous souhaitez participer \u00e0 des comp\u00e9titions officielles ou courir \u00e0 l'\u00e9tranger, vous devez \u00eatre titulaire d'une <strong>licence compl\u00e8te<\/strong>.<\/p><p>La m\u00eame assurance que la licence Member, mais avec en plus le droit de participer \u00e0 TOUS les championnats belges dans plusieurs, voire toutes les disciplines et classes. Elle donne \u00e9galement acc\u00e8s \u00e0 l'EFRA.<\/p><div id=\"ConnectiveDocSignExtentionInstalled\" data-extension-version=\"1.0.4\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db60af9 e-flex e-con-boxed e-con e-child\" data-id=\"db60af9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-afc9fee e-con-full e-flex e-con e-child\" data-id=\"afc9fee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24bf22a elementor-widget elementor-widget-heading\" data-id=\"24bf22a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C: Participation europ\u00e9enne EFRA:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d6dedeb e-con-full e-flex e-con e-child\" data-id=\"d6dedeb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23da97a elementor-widget elementor-widget-text-editor\" data-id=\"23da97a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Celui-ci sera d\u00e9duit du paiement de la r\u00e9servation pour les comp\u00e9titions Efra ou Ifmar. <br>Votre demande doit parvenir au secr\u00e9tariat au plus tard le 31 d\u00e9cembre et le paiement doit \u00eatre effectu\u00e9 au plus tard le 15 janvier. <br>Les demandes ne seront accept\u00e9es que si vous \u00eates titulaire d'une licence compl\u00e8te. <br>Les places autoris\u00e9es par l'Efra ou l'Ifmar sont attribu\u00e9es par les pr\u00e9sidents de section, en tenant compte des r\u00e9sultats obtenus pr\u00e9c\u00e9demment.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fd5d11 e-flex e-con-boxed e-con e-child\" data-id=\"4fd5d11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-78b6a9a e-con-full e-flex e-con e-child\" data-id=\"78b6a9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a4ef85 elementor-widget elementor-widget-heading\" data-id=\"1a4ef85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Attention:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74ec782 e-con-full e-flex e-con e-child\" data-id=\"74ec782\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c086355 elementor-widget elementor-widget-text-editor\" data-id=\"c086355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alle aansluitingen\/licenties dienen via een erkende club te gebeuren.<br \/>Toutes les affiliations\/licences doivent \u00eatre effectu\u00e9es par l'interm\u00e9diaire d'un club agr\u00e9\u00e9.\nLes pilotes qui participent \u00e0 une discipline disput\u00e9e sur un circuit asphalt\u00e9 doivent obtenir une licence aupr\u00e8s d'un club organisateur disposant d'un circuit asphalt\u00e9.\nLes personnes repr\u00e9sentant des entreprises commerciales du secteur du mod\u00e9lisme peuvent devenir membres \u00e0 ce titre sans passer par un club (voir r\u00e8glement interne, art. 2.6).<br \/>Toutes les affiliations\/licences doivent \u00eatre effectu\u00e9es par l'interm\u00e9diaire d'un club agr\u00e9\u00e9.\nLes pilotes qui participent \u00e0 une discipline disput\u00e9e sur un circuit asphalt\u00e9 doivent obtenir une licence aupr\u00e8s d'un club organisateur disposant d'un circuit asphalt\u00e9.\nLes personnes repr\u00e9sentant des entreprises commerciales du secteur du mod\u00e9lisme peuvent devenir membres \u00e0 ce titre sans passer par un club (voir r\u00e8glement interne, art. 2.6).<\/p><div id=\"ConnectiveDocSignExtentionInstalled\" data-extension-version=\"1.0.4\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Lidmaatschap A: MEMBER licentie: 10\u20ac De basis aansluiting is de member licentie. Iedereen die op een circuit buiten de toeschouwers zone vertoeft MOET deze licentie met de eraan verbonden complementaire verzekeringen hebben, ze is geldig op alle vaste en tijdelijke omlopen van door de FBA erkende clubs, op trainingen, open wedstrijden en bij het uitvoeren [&hellip;]<\/p>","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-82","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fba-rc.be\/fr\/wp-json\/wp\/v2\/pages\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fba-rc.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fba-rc.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fba-rc.be\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fba-rc.be\/fr\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":27,"href":"https:\/\/fba-rc.be\/fr\/wp-json\/wp\/v2\/pages\/82\/revisions"}],"predecessor-version":[{"id":1893,"href":"https:\/\/fba-rc.be\/fr\/wp-json\/wp\/v2\/pages\/82\/revisions\/1893"}],"wp:attachment":[{"href":"https:\/\/fba-rc.be\/fr\/wp-json\/wp\/v2\/media?parent=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}